{"id":144,"date":"2026-05-06T08:36:02","date_gmt":"2026-05-06T08:36:02","guid":{"rendered":"https:\/\/nu50:8890\/?post_type=team&#038;p=144"},"modified":"2026-05-06T08:36:02","modified_gmt":"2026-05-06T08:36:02","slug":"juergen-mies","status":"publish","type":"team","link":"https:\/\/nu50.klickdrauf.at\/de\/team\/juergen-mies\/","title":{"rendered":"J\u00fcrgen Mies"},"excerpt":{"rendered":"<p>Lorem ipsum dolor sit amet, consetetur sadipscing<\/p>\n","protected":false},"featured_media":27,"template":"","class_list":["post-144","team","type-team","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>J\u00fcrgen Mies - nu50<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nu50.klickdrauf.at\/de\/team\/juergen-mies\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J\u00fcrgen Mies - nu50\" \/>\n<meta property=\"og:description\" content=\"Lorem ipsum dolor sit amet, consetetur sadipscing\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nu50.klickdrauf.at\/de\/team\/juergen-mies\/\" \/>\n<meta property=\"og:site_name\" content=\"nu50\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nu50.klickdrauf.at\/wp-content\/uploads\/2026\/05\/8fdd0729e53dbdf50e1877e49fb4fdd4.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"245\" \/>\n\t<meta property=\"og:image:height\" content=\"345\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/team\\\/juergen-mies\\\/\",\"url\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/team\\\/juergen-mies\\\/\",\"name\":\"J\u00fcrgen Mies - nu50\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/team\\\/juergen-mies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/team\\\/juergen-mies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/8fdd0729e53dbdf50e1877e49fb4fdd4.webp\",\"datePublished\":\"2026-05-06T08:36:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/team\\\/juergen-mies\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nu50.klickdrauf.at\\\/team\\\/juergen-mies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/team\\\/juergen-mies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/8fdd0729e53dbdf50e1877e49fb4fdd4.webp\",\"contentUrl\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/8fdd0729e53dbdf50e1877e49fb4fdd4.webp\",\"width\":245,\"height\":345},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/team\\\/juergen-mies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Team\",\"item\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/team\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"J\u00fcrgen Mies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/de\\\/\",\"name\":\"nu50\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/de\\\/#organization\",\"name\":\"nu50\",\"url\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Logo_colored.svg\",\"contentUrl\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Logo_colored.svg\",\"width\":1,\"height\":1,\"caption\":\"nu50\"},\"image\":{\"@id\":\"https:\\\/\\\/nu50.klickdrauf.at\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"J\u00fcrgen Mies - nu50","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nu50.klickdrauf.at\/de\/team\/juergen-mies\/","og_locale":"de_DE","og_type":"article","og_title":"J\u00fcrgen Mies - nu50","og_description":"Lorem ipsum dolor sit amet, consetetur sadipscing","og_url":"https:\/\/nu50.klickdrauf.at\/de\/team\/juergen-mies\/","og_site_name":"nu50","og_image":[{"width":245,"height":345,"url":"https:\/\/nu50.klickdrauf.at\/wp-content\/uploads\/2026\/05\/8fdd0729e53dbdf50e1877e49fb4fdd4.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nu50.klickdrauf.at\/team\/juergen-mies\/","url":"https:\/\/nu50.klickdrauf.at\/team\/juergen-mies\/","name":"J\u00fcrgen Mies - nu50","isPartOf":{"@id":"https:\/\/nu50.klickdrauf.at\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nu50.klickdrauf.at\/team\/juergen-mies\/#primaryimage"},"image":{"@id":"https:\/\/nu50.klickdrauf.at\/team\/juergen-mies\/#primaryimage"},"thumbnailUrl":"https:\/\/nu50.klickdrauf.at\/wp-content\/uploads\/2026\/05\/8fdd0729e53dbdf50e1877e49fb4fdd4.webp","datePublished":"2026-05-06T08:36:02+00:00","breadcrumb":{"@id":"https:\/\/nu50.klickdrauf.at\/team\/juergen-mies\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nu50.klickdrauf.at\/team\/juergen-mies\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nu50.klickdrauf.at\/team\/juergen-mies\/#primaryimage","url":"https:\/\/nu50.klickdrauf.at\/wp-content\/uploads\/2026\/05\/8fdd0729e53dbdf50e1877e49fb4fdd4.webp","contentUrl":"https:\/\/nu50.klickdrauf.at\/wp-content\/uploads\/2026\/05\/8fdd0729e53dbdf50e1877e49fb4fdd4.webp","width":245,"height":345},{"@type":"BreadcrumbList","@id":"https:\/\/nu50.klickdrauf.at\/team\/juergen-mies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nu50.klickdrauf.at\/de\/"},{"@type":"ListItem","position":2,"name":"Team","item":"https:\/\/nu50.klickdrauf.at\/team\/"},{"@type":"ListItem","position":3,"name":"J\u00fcrgen Mies"}]},{"@type":"WebSite","@id":"https:\/\/nu50.klickdrauf.at\/de\/#website","url":"https:\/\/nu50.klickdrauf.at\/de\/","name":"nu50","description":"","publisher":{"@id":"https:\/\/nu50.klickdrauf.at\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nu50.klickdrauf.at\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/nu50.klickdrauf.at\/de\/#organization","name":"nu50","url":"https:\/\/nu50.klickdrauf.at\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nu50.klickdrauf.at\/de\/#\/schema\/logo\/image\/","url":"https:\/\/nu50.klickdrauf.at\/wp-content\/uploads\/2026\/05\/Logo_colored.svg","contentUrl":"https:\/\/nu50.klickdrauf.at\/wp-content\/uploads\/2026\/05\/Logo_colored.svg","width":1,"height":1,"caption":"nu50"},"image":{"@id":"https:\/\/nu50.klickdrauf.at\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nu50.klickdrauf.at\/de\/wp-json\/wp\/v2\/team\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nu50.klickdrauf.at\/de\/wp-json\/wp\/v2\/team"}],"about":[{"href":"https:\/\/nu50.klickdrauf.at\/de\/wp-json\/wp\/v2\/types\/team"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nu50.klickdrauf.at\/de\/wp-json\/wp\/v2\/media\/27"}],"wp:attachment":[{"href":"https:\/\/nu50.klickdrauf.at\/de\/wp-json\/wp\/v2\/media?parent=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}